{"id":12,"date":"2025-06-27T14:17:30","date_gmt":"2025-06-27T12:17:30","guid":{"rendered":"https:\/\/www.endo-nova.eu\/?page_id=12"},"modified":"2025-11-14T18:22:53","modified_gmt":"2025-11-14T17:22:53","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Call to Action&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F4F3E6&#8243; custom_padding=&#8221;||0px|||&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_4_font=&#8221;&#8211;et_global_heading_font|700||on|||||&#8221; header_4_text_color=&#8221;#B6B028&#8243; header_4_font_size=&#8221;24px&#8221; header_4_letter_spacing=&#8221;1px&#8221; header_4_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Chi Siamo<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_font=&#8221;&#8211;et_global_heading_font|600|||||||&#8221; header_text_color=&#8221;#0E2D41&#8243; header_font_size=&#8221;64px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Partner di fiducia per la gestione delle tue apparecchiature elettromedicali<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#0E2D41&#8243; text_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p data-start=\"355\" data-end=\"659\">In ENDO NOVA crediamo che il valore di una partnership si misuri dalla qualit\u00e0 dei risultati e dalla fiducia che si costruisce giorno dopo giorno. Fondata nel 2004, \u00e8 il punto di riferimento per la <strong>riparazione e manutenzione di apparecchiature mediche, in particolare sonde ecografiche ed endoscopi flessibili<\/strong>.<\/p>\n<p data-start=\"661\" data-end=\"841\">Il nostro impegno \u00e8 offrire <strong data-start=\"689\" data-end=\"727\">soluzioni tecniche di alto livello<\/strong>, che riducano al minimo i tempi di inattivit\u00e0 e assicurino la <strong data-start=\"790\" data-end=\"840\">continuit\u00e0 operativa delle strutture sanitarie<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Call to Action&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F4F3E6&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0) 50%|#0e2d41 50%&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; admin_label=&#8221;Background photo&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_image=&#8221;off&#8221; width=&#8221;90%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;80%&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;none&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/www.endo-nova.eu\/wp-content\/uploads\/2025\/10\/riparazioni-apparecchiature-elettromedicali.webp&#8221; custom_padding=&#8221;300px||300px||true|false&#8221; custom_padding_tablet=&#8221;300px||300px||true|false&#8221; custom_padding_phone=&#8221;100px||100px||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;80px|80px|80px|80px|true|true&#8221; custom_padding_tablet=&#8221;80px|0px|80px|0px|true|true&#8221; custom_padding_phone=&#8221;40px|0px|40px|0px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; border_color_left=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; text_font=&#8221;&#8211;et_global_body_font||||||||&#8221; text_text_color=&#8221;#000000&#8243; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.4em&#8221; background_color=&#8221;#799395&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;40px||||false|false&#8221; custom_margin_tablet=&#8221;40px||||false|false&#8221; custom_margin_phone=&#8221;40px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; custom_margin__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<h2>Esperienza tecnica<br \/>al tuo Servizio<\/h2>\n<p>Con oltre <strong>12.000 dispositivi riparati<\/strong>, ENDONOVA ha sviluppato una conoscenza approfondita delle pi\u00f9 diverse tecnologie e dei principali marchi del settore. I nostri tecnici sono formati per diagnosticare rapidamente le problematiche e intervenire in modo <strong>preciso, sicuro ed efficiente<\/strong>.<\/p>\n<p>Disponiamo di <strong>laboratori interni all\u2019avanguardia<\/strong>, attrezzati per affrontare anche le riparazioni pi\u00f9 complesse. Collaboriamo inoltre con una <strong>rete di partner specializzati<\/strong>, per garantire un servizio completo e capillare.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Stats&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0E2D41&#8243; custom_margin=&#8221;-2px||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;60px|48px|60px|48px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Competenza tecnica costantemente aggiornata&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf013;||fa||900&#8243; icon_color=&#8221;#B6B028&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Affidabilit\u00e0 costruita in anni di esperienza sul campo&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf4be;||fa||900&#8243; icon_color=&#8221;#B6B028&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Velocit\u00e0 operativa senza compromessi sulla qualit\u00e0&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;#B6B028&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Partnership durature, basate su trasparenza e ascolto&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf2b5;||fa||400&#8243; icon_color=&#8221;#B6B028&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0E2D41&#8243; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_4_font=&#8221;Inter|700||on|||||&#8221; header_4_text_color=&#8221;#FFFFFF&#8221; header_4_font_size=&#8221;24px&#8221; header_4_letter_spacing=&#8221;1px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Cosa offriamo<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_2_font=&#8221;Inter|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>La nostra missione:<br \/>Attenzione, Dialogo, Efficienza e Affidabilit\u00e0.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.8em&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>\n  Ogni realt\u00e0 sanitaria ha esigenze diverse. Per questo proponiamo un<br \/>\n  <strong>approccio ibrido<\/strong>, che combina interventi personalizzati,<br \/>\n  <strong>soluzioni Repair\/Exchange<\/strong> e<br \/>\n  <strong>manutenzione preventiva<\/strong>, il tutto con<br \/>\n  <strong>tempi di risposta rapidi e prezzi competitivi<\/strong>.\n<\/p>\n<p>\n  Che si tratti di un <strong>piccolo ambulatorio<\/strong> o di una <strong>grande struttura ospedaliera<\/strong>, il nostro obiettivo resta lo stesso: <strong>assicurare la piena funzionalit\u00e0<\/strong> delle <strong>apparecchiature elettromedicali<\/strong>, proteggendo il <strong>benessere del paziente<\/strong> e l\u2019<strong>efficienza del flusso clinico<\/strong>.\n<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi SiamoPartner di fiducia per la gestione delle tue apparecchiature elettromedicaliIn ENDO NOVA crediamo che il valore di una partnership si misuri dalla qualit\u00e0 dei risultati e dalla fiducia che si costruisce giorno dopo giorno. Fondata nel 2004, \u00e8 il punto di riferimento per la riparazione e manutenzione di apparecchiature mediche, in particolare sonde ecografiche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chi siamo - Endonova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chi siamo - Endonova\" \/>\n<meta property=\"og:description\" content=\"Chi SiamoPartner di fiducia per la gestione delle tue apparecchiature elettromedicaliIn ENDO NOVA crediamo che il valore di una partnership si misuri dalla qualit\u00e0 dei risultati e dalla fiducia che si costruisce giorno dopo giorno. Fondata nel 2004, \u00e8 il punto di riferimento per la riparazione e manutenzione di apparecchiature mediche, in particolare sonde ecografiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Endonova\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T17:22:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/chi-siamo\\\/\",\"url\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/chi-siamo\\\/\",\"name\":\"Chi siamo - Endonova\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#website\"},\"datePublished\":\"2025-06-27T12:17:30+00:00\",\"dateModified\":\"2025-11-14T17:22:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/chi-siamo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/chi-siamo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/chi-siamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chi siamo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/\",\"name\":\"Endonova\",\"description\":\"Centra la soluzione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#organization\",\"name\":\"Endonova\",\"url\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.endo-nova.eu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo_endonova_hires.png\",\"contentUrl\":\"https:\\\/\\\/www.endo-nova.eu\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo_endonova_hires.png\",\"width\":765,\"height\":470,\"caption\":\"Endonova\"},\"image\":{\"@id\":\"https:\\\/\\\/www.endo-nova.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chi siamo - Endonova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/","og_locale":"it_IT","og_type":"article","og_title":"Chi siamo - Endonova","og_description":"Chi SiamoPartner di fiducia per la gestione delle tue apparecchiature elettromedicaliIn ENDO NOVA crediamo che il valore di una partnership si misuri dalla qualit\u00e0 dei risultati e dalla fiducia che si costruisce giorno dopo giorno. Fondata nel 2004, \u00e8 il punto di riferimento per la riparazione e manutenzione di apparecchiature mediche, in particolare sonde ecografiche [&hellip;]","og_url":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/","og_site_name":"Endonova","article_modified_time":"2025-11-14T17:22:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/","url":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/","name":"Chi siamo - Endonova","isPartOf":{"@id":"https:\/\/www.endo-nova.eu\/it\/#website"},"datePublished":"2025-06-27T12:17:30+00:00","dateModified":"2025-11-14T17:22:53+00:00","breadcrumb":{"@id":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.endo-nova.eu\/it\/chi-siamo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.endo-nova.eu\/it\/chi-siamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.endo-nova.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Chi siamo"}]},{"@type":"WebSite","@id":"https:\/\/www.endo-nova.eu\/it\/#website","url":"https:\/\/www.endo-nova.eu\/it\/","name":"Endonova","description":"Centra la soluzione","publisher":{"@id":"https:\/\/www.endo-nova.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.endo-nova.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.endo-nova.eu\/it\/#organization","name":"Endonova","url":"https:\/\/www.endo-nova.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.endo-nova.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.endo-nova.eu\/wp-content\/uploads\/2025\/07\/logo_endonova_hires.png","contentUrl":"https:\/\/www.endo-nova.eu\/wp-content\/uploads\/2025\/07\/logo_endonova_hires.png","width":765,"height":470,"caption":"Endonova"},"image":{"@id":"https:\/\/www.endo-nova.eu\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":30,"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":31661,"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/pages\/12\/revisions\/31661"}],"wp:attachment":[{"href":"https:\/\/www.endo-nova.eu\/it\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}